{"id":1592,"date":"2015-09-14T22:30:17","date_gmt":"2015-09-14T20:30:17","guid":{"rendered":"https:\/\/www.trend4ward.de\/trendblog\/?p=1592"},"modified":"2017-05-11T17:01:49","modified_gmt":"2017-05-11T15:01:49","slug":"neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen","status":"publish","type":"post","link":"https:\/\/www.trend4ward.de\/trendblog\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\/","title":{"rendered":"Neuer Luxus mit weniger M\u00f6beln: Wie Minimalisten wohnen"},"content":{"rendered":"<p><strong>\u201eBesitz belastet\u201c und \u201eWeniger ist mehr\u201c \u2013 diese Volksweisheiten sind wohlgemein bekannt. Einige, die es damit ernst meinen, sind so genannte \u201eMinimalisten\u201c. Sie reduzieren ihre Besitzt\u00fcmer, um gl\u00fccklicher zu leben. Wie das geht, zeigen wir hier.<\/strong><\/p>\n<p><!--more--><\/p>\n<figure id=\"attachment_1597\" aria-describedby=\"caption-attachment-1597\" style=\"width: 220px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/09\/Bildschirmfoto-2015-09-14-um-22.41.25.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1597 size-medium\" src=\"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/09\/Bildschirmfoto-2015-09-14-um-22.41.25-220x300.png\" alt=\"minimalismus\" width=\"220\" height=\"300\" srcset=\"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/09\/Bildschirmfoto-2015-09-14-um-22.41.25-220x300.png 220w, https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/09\/Bildschirmfoto-2015-09-14-um-22.41.25-44x60.png 44w, https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/09\/Bildschirmfoto-2015-09-14-um-22.41.25.png 511w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/><\/a><figcaption id=\"caption-attachment-1597\" class=\"wp-caption-text\">Foto: Max Bahr<\/figcaption><\/figure>\n<p>Sie propagieren bewussten Konsum und ben\u00f6tigen zum Wohnen nicht viel mehr als ein Bett. Was sie antreibt, so zu leben, verraten zwei Minimalisten und eine Raumsoziologin.<\/p>\n<p>\u201eIm ersten Schritt geht es mir darum, Bewusstsein zu schaffen, f\u00fcr die Sachen, die mich interessieren\u201c, sagt Sebastian Michel, 25, aus Berlin-Neuk\u00f6lln, der seit vier Jahren minimalistisch lebt. Die Frage \u201eWas macht mich gl\u00fccklich?\u201c steht hierbei an oberster Stelle. \u00dcber diese und viele weitere Fragen, die seine Art zu Leben beinhalteten, stellte er sich nach einem Krankheitsfall in der Familie. \u201eIch wollte von Dingen aus meiner Kindheit loslassen, mich von mehr als die H\u00e4lfte meiner B\u00fccher, DVDs und Kleidungsst\u00fccke trennen\u201c, erz\u00e4hlt er. Dinge, die wie eine Last an ihm hingen. Nach der Entr\u00fcmpelungsaktion empfand er als erstes Gl\u00fcck. \u201eOhne die vielen Sachen hat es sich einfach besser angef\u00fchlt.\u201c Um B\u00fccher zu lesen nutzt der Kommunikationsassistent und Blogger heute seinen E-Book-Reader. Das Regal mit B\u00fcchern hat er mittlerweile aufgegeben. In seinem 20 Quadratmeter gro\u00dfen WG-Zimmer befinden sich nur noch Bett, Kleiderstange, Leuchte sowie ein Bild und eine Box mit \u00fcbrig gebliebenem Kleinkram. Schreibtisch und St\u00fchle braucht er nicht. Daf\u00fcr k\u00f6nne man schlie\u00dflich auch nach drau\u00dfen gehen. Denn, so erkl\u00e4rt er: \u201eMein Zimmer nutze ich zum Entspannen.\u201c Aus seinen ersten Erfahrungen mit dem Minimalismus ist heute eine Haltung, ein alternativer Lebensstil geworden. \u201eEs geht auch darum, bewusster zu Leben und sich beispielsweise von Routinen des Alltags zu l\u00f6sen\u201c, sagt er.<\/p>\n<p>Bei Michael Klumb, 35, Augenoptiker, aus Bergisch Gladbach bei K\u00f6ln, hat alles in seinem jetzigen Ein-Zimmer-Appartement angefangen. \u201e2011 stand ich in der Wohnung und sagte mir, so kann es nicht weitergehen. Es ist hier nicht mehr gem\u00fctlich mit so vielen Dingen\u201c, erinnert er sich. Bis dato hatte Klumb 2500 CDs im Regal und viel zu viel von anderem auch, ob B\u00fccher, Kleidungsst\u00fccke oder Gew\u00fcrzdosen. Hinzu kamen nicht genutzte M\u00f6bel wie ein Tisch mit zwei St\u00fchlen. \u201eAlles war zugestellt\u201c, erz\u00e4hlt er. \u201eIch kam nicht mehr hinterher aufzur\u00e4umen.\u201c Er begann nach einem Weg zu suchen, seine Wohnsituation zu \u00e4ndern, las damalige Bestseller wie \u201eSimplify your life\u201c von W. T. K\u00fcstenmacher und L. J. Seifert. Das ging ihm aber alles nicht weit genug. Bis er amerikanische Blogger entdeckte, die \u00fcber Minimalismus als eine Art von Lebensstil schrieben. Klumb mistete im gro\u00dfen Stil aus. Ein Schlafsofa, ein kleiner Kleiderschrank sowie eine Schrankwand, Fernseher und wenige Ordnern sind \u00fcbrig geblieben. B\u00fccher gibt es nur noch wenige, als Dekoration gen\u00fcgen ihm ein Bild an der Wand und eine Orchidee. \u201eMir gibt der neu gewonnene Platz das Gef\u00fchl von Klarheit und Befreitheit\u201c, sagt er und empfiehlt f\u00fcr Unentschlossene: \u201eWer nicht gleich alles weggeben will, kann nichtgenutzte Dinge in eine Kiste packen und f\u00fcr eine oder mehrere Wochen in die Abstellkammer stellen, um zu pr\u00fcfen, ob einem die Sachen fehlen.\u201c Wenn nicht, kann man sich von ihnen trennen.<\/p>\n<p>Klumb, der sich in sozialen Netzwerken und auf Veranstaltungen mit anderen Minimalisten austauscht, wei\u00df, dass der Leidensdruck bei vielen vorher sehr hoch gewesen ist. \u201eZu viel Stress kann ein Ausl\u00f6ser f\u00fcr Minimalismus sein\u201c, sagt er. \u201eSowie der Wunsch auf verschiedene Weise loszulassen und gl\u00fccklicher zu leben.\u201c<\/p>\n\r<div class=\"GARD gard_basic_mode\" id=\"google-ads-62PW\"><script >\radUnit = document.getElementById(\"google-ads-62PW\");\radWidth = adUnit.offsetWidth;\r\rif ( adWidth >= 999999 ) {\r\/* GETTING THE FIRST IF OUT OF THE WAY *\/ \r} else {\rgoogle_ad_slot = \"0\";\radUnit.style.display = \"none\";\r}\radUnit.className = adUnit.className + \" ad_unit \" + tag;\rgoogle_ad_client = \"ca-pub-6170969419645551\";\radUnit.style.cssFloat  = \"right\";\radUnit.style.styleFloat  = \"right\";\radUnit.style.margin = \"0 0 10px 10px\";\radUnit.style.textAlign = \"initial\";\rgoogle_color_border = \"FFFFFF\";\rgoogle_color_bg = \"FFFFFF\";\rgoogle_color_link = \"999999\";\rgoogle_color_url = \"99cc33\";\rgoogle_color_text = \"666666\";\rgoogle_ui_features = \"rc:\";\r<\/script>\r<script  src=\"\/\/pagead2.googlesyndication.com\/pagead\/show_ads.js\"><\/script>\r<\/div>Dies kann auch Christiane Varga, Raumsoziologin beim Zukunftsinstitut best\u00e4tigen. \u201eIn unserer globalen, komplexen und digital-vernetzten Welt wird es schwerer, sich auf das Wesentliche zu konzentrieren\u201c, sagt Varga. N\u00e4mlich auf sich selbst. Materielle Dinge lenken beim Fokussieren auf das eigene Ich besonders ab. So scheint es folgerichtig, dass \u201eder neue Luxus das Gegenteil von Protzigkeit ist\u201c, sagt sie. Denn Minimalisten schaffen ihre Identit\u00e4t durch Abgrenzung: mit weniger Konsum und wenigeren M\u00f6beln. Ein opulenter Schrank, ein vollgestopftes Regal und zu viel Dekoration st\u00f6ren auf dem Weg zum Gl\u00fccklichsein. Auch kr\u00e4ftige Farben k\u00f6nnen eine ungew\u00fcnschte Raumwirkung verursachen. Asketischere M\u00f6bel z. B. im Bauhaus Design oder im skandinavischen Stil wirken laut der Expertin eher f\u00f6rderlich f\u00fcr die Kreativit\u00e4t und den Weg zu sich. Dazu passen dann die Farben Wei\u00df, Grau, Schwarz, so genannte Nicht-Farben, die hier bewusst keine Wirkung erzielen sollen, erkl\u00e4rt sie.<\/p>\n<p>Jedoch ist es nicht so, dass Minimalisten nichts mehr kaufen. \u201eEs geht um bewussten Konsum und dies hei\u00dft meistens weniger\u201c, erkl\u00e4rt Michael Klumb. Neuanschaffungen sollen m\u00f6glichst lange halten, ein schickes Design aufweisen und in ihrer Funktion n\u00fctzlich sein. Die Frage \u201eBrauche ich das \u00fcberhaupt?\u201c wird hier jedes Mal aufs Neue beantwortet. Denn \u201eDinge, die man kauft, bedeuten etwas\u201c, sagt Sebastian Michel. \u201eSie sind nicht einfach so da, nur weil man sie sich leisten konnte.\u201c Minimalismus hat so auch viel mit einem nachhaltigeren Lebensstil gemein. Ein Beispiel ist das in Mode gekommene \u201eUp-Cycling\u201c, sagt Michael Klumb, die neue Art des Heimwerkens, bei der aus alten Gebrauchsgegenst\u00e4nden etwas Neues geschaffen wird, wie beispielsweise aus alten Euro-Paletten eine gem\u00fctliche Sitzbank.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eBesitz belastet\u201c und \u201eWeniger ist mehr\u201c \u2013 diese Volksweisheiten sind wohlgemein bekannt. Einige, die es damit ernst meinen, sind so genannte \u201eMinimalisten\u201c. Sie reduzieren ihre Besitzt\u00fcmer, um gl\u00fccklicher zu leben. Wie das geht, zeigen wir hier.<\/p>\n","protected":false},"author":1,"featured_media":2230,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[76,3,15],"tags":[107,48,198,188,93,34,35],"class_list":["post-1592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-leben-und-gesellschaft","category-trendbarometer","category-wohnen","tag-lebensstil","tag-moebel","tag-nachhaltig-und-oekologisch","tag-upcycling","tag-wohntrends","tag-zielgruppen","tag-zukunft"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neuer Luxus mit weniger M\u00f6beln: Wie Minimalisten wohnen &#8226; trendBlog \u2013 Wohnen, Reisen, Leben und Kultur<\/title>\n<meta name=\"description\" content=\"Minimalisten reduzieren ihre Besitzt\u00fcmer, um gl\u00fccklicher zu leben. Was sie antreibt, verraten sie hier.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trend4ward.de\/trendblog\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neuer Luxus mit weniger M\u00f6beln: Wie Minimalisten wohnen &#8226; trendBlog \u2013 Wohnen, Reisen, Leben und Kultur\" \/>\n<meta property=\"og:description\" content=\"Minimalisten reduzieren ihre Besitzt\u00fcmer, um gl\u00fccklicher zu leben. Was sie antreibt, verraten sie hier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trend4ward.de\/trendblog\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\/\" \/>\n<meta property=\"og:site_name\" content=\"trendBlog \u2013 Wohnen, Reisen, Leben und Kultur\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-14T20:30:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-11T15:01:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/09\/Wand.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1014\" \/>\n\t<meta property=\"og:image:height\" content=\"495\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Evelyn Steinbach\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Evelyn Steinbach\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\\\/\"},\"author\":{\"name\":\"Evelyn Steinbach\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/#\\\/schema\\\/person\\\/c65dd8afd2fda04893d121f31b2a8ea4\"},\"headline\":\"Neuer Luxus mit weniger M\u00f6beln: Wie Minimalisten wohnen\",\"datePublished\":\"2015-09-14T20:30:17+00:00\",\"dateModified\":\"2017-05-11T15:01:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\\\/\"},\"wordCount\":882,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/#\\\/schema\\\/person\\\/c65dd8afd2fda04893d121f31b2a8ea4\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/Wand.jpg\",\"keywords\":[\"Lebensstil\",\"M\u00f6bel\",\"Nachhaltig &amp; \u00f6kologisch\",\"Upcycling\",\"Wohntrends\",\"Zielgruppen\",\"Zukunft\"],\"articleSection\":[\"Leben &amp; Gesellschaft\",\"trendBarometer\",\"Wohnen &amp; Einrichten\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\\\/\",\"url\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\\\/\",\"name\":\"Neuer Luxus mit weniger M\u00f6beln: Wie Minimalisten wohnen &#8226; trendBlog \u2013 Wohnen, Reisen, Leben und Kultur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/Wand.jpg\",\"datePublished\":\"2015-09-14T20:30:17+00:00\",\"dateModified\":\"2017-05-11T15:01:49+00:00\",\"description\":\"Minimalisten reduzieren ihre Besitzt\u00fcmer, um gl\u00fccklicher zu leben. Was sie antreibt, verraten sie hier.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/Wand.jpg\",\"contentUrl\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/Wand.jpg\",\"width\":1014,\"height\":495},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neuer Luxus mit weniger M\u00f6beln: Wie Minimalisten wohnen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/#website\",\"url\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/\",\"name\":\"trendBlog \u2013 Wohnen, Reisen, Leben und Kultur\",\"description\":\"Portr\u00e4ts, Reportagen, Ratgeber. Seit 2009. Von Evelyn Steinbach.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/#\\\/schema\\\/person\\\/c65dd8afd2fda04893d121f31b2a8ea4\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/#\\\/schema\\\/person\\\/c65dd8afd2fda04893d121f31b2a8ea4\",\"name\":\"Evelyn Steinbach\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/cropped-cropped-IMG_6744-e1692617617527.png\",\"url\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/cropped-cropped-IMG_6744-e1692617617527.png\",\"contentUrl\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/cropped-cropped-IMG_6744-e1692617617527.png\",\"width\":200,\"height\":183,\"caption\":\"Evelyn Steinbach\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/cropped-cropped-IMG_6744-e1692617617527.png\"},\"sameAs\":[\"http:\\\/\\\/www.trend4ward.de\"],\"url\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/author\\\/eve\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neuer Luxus mit weniger M\u00f6beln: Wie Minimalisten wohnen &#8226; trendBlog \u2013 Wohnen, Reisen, Leben und Kultur","description":"Minimalisten reduzieren ihre Besitzt\u00fcmer, um gl\u00fccklicher zu leben. Was sie antreibt, verraten sie hier.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trend4ward.de\/trendblog\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\/","og_locale":"de_DE","og_type":"article","og_title":"Neuer Luxus mit weniger M\u00f6beln: Wie Minimalisten wohnen &#8226; trendBlog \u2013 Wohnen, Reisen, Leben und Kultur","og_description":"Minimalisten reduzieren ihre Besitzt\u00fcmer, um gl\u00fccklicher zu leben. Was sie antreibt, verraten sie hier.","og_url":"https:\/\/www.trend4ward.de\/trendblog\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\/","og_site_name":"trendBlog \u2013 Wohnen, Reisen, Leben und Kultur","article_published_time":"2015-09-14T20:30:17+00:00","article_modified_time":"2017-05-11T15:01:49+00:00","og_image":[{"width":1014,"height":495,"url":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/09\/Wand.jpg","type":"image\/jpeg"}],"author":"Evelyn Steinbach","twitter_misc":{"Verfasst von":"Evelyn Steinbach","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.trend4ward.de\/trendblog\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\/#article","isPartOf":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\/"},"author":{"name":"Evelyn Steinbach","@id":"https:\/\/www.trend4ward.de\/trendblog\/#\/schema\/person\/c65dd8afd2fda04893d121f31b2a8ea4"},"headline":"Neuer Luxus mit weniger M\u00f6beln: Wie Minimalisten wohnen","datePublished":"2015-09-14T20:30:17+00:00","dateModified":"2017-05-11T15:01:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\/"},"wordCount":882,"commentCount":1,"publisher":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/#\/schema\/person\/c65dd8afd2fda04893d121f31b2a8ea4"},"image":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/09\/Wand.jpg","keywords":["Lebensstil","M\u00f6bel","Nachhaltig &amp; \u00f6kologisch","Upcycling","Wohntrends","Zielgruppen","Zukunft"],"articleSection":["Leben &amp; Gesellschaft","trendBarometer","Wohnen &amp; Einrichten"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.trend4ward.de\/trendblog\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.trend4ward.de\/trendblog\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\/","url":"https:\/\/www.trend4ward.de\/trendblog\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\/","name":"Neuer Luxus mit weniger M\u00f6beln: Wie Minimalisten wohnen &#8226; trendBlog \u2013 Wohnen, Reisen, Leben und Kultur","isPartOf":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\/#primaryimage"},"image":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/09\/Wand.jpg","datePublished":"2015-09-14T20:30:17+00:00","dateModified":"2017-05-11T15:01:49+00:00","description":"Minimalisten reduzieren ihre Besitzt\u00fcmer, um gl\u00fccklicher zu leben. Was sie antreibt, verraten sie hier.","breadcrumb":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trend4ward.de\/trendblog\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.trend4ward.de\/trendblog\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\/#primaryimage","url":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/09\/Wand.jpg","contentUrl":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/09\/Wand.jpg","width":1014,"height":495},{"@type":"BreadcrumbList","@id":"https:\/\/www.trend4ward.de\/trendblog\/neuer-luxus-mit-weniger-moebeln-wie-minimalisten-wohnen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.trend4ward.de\/trendblog\/"},{"@type":"ListItem","position":2,"name":"Neuer Luxus mit weniger M\u00f6beln: Wie Minimalisten wohnen"}]},{"@type":"WebSite","@id":"https:\/\/www.trend4ward.de\/trendblog\/#website","url":"https:\/\/www.trend4ward.de\/trendblog\/","name":"trendBlog \u2013 Wohnen, Reisen, Leben und Kultur","description":"Portr\u00e4ts, Reportagen, Ratgeber. Seit 2009. Von Evelyn Steinbach.","publisher":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/#\/schema\/person\/c65dd8afd2fda04893d121f31b2a8ea4"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trend4ward.de\/trendblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.trend4ward.de\/trendblog\/#\/schema\/person\/c65dd8afd2fda04893d121f31b2a8ea4","name":"Evelyn Steinbach","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2020\/11\/cropped-cropped-IMG_6744-e1692617617527.png","url":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2020\/11\/cropped-cropped-IMG_6744-e1692617617527.png","contentUrl":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2020\/11\/cropped-cropped-IMG_6744-e1692617617527.png","width":200,"height":183,"caption":"Evelyn Steinbach"},"logo":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2020\/11\/cropped-cropped-IMG_6744-e1692617617527.png"},"sameAs":["http:\/\/www.trend4ward.de"],"url":"https:\/\/www.trend4ward.de\/trendblog\/author\/eve\/"}]}},"jetpack_featured_media_url":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/09\/Wand.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/posts\/1592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/comments?post=1592"}],"version-history":[{"count":7,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/posts\/1592\/revisions"}],"predecessor-version":[{"id":2235,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/posts\/1592\/revisions\/2235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/media\/2230"}],"wp:attachment":[{"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/media?parent=1592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/categories?post=1592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/tags?post=1592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}