{"id":1665,"date":"2015-10-25T14:32:34","date_gmt":"2015-10-25T13:32:34","guid":{"rendered":"https:\/\/www.trend4ward.de\/trendblog\/?p=1665"},"modified":"2019-05-06T16:31:22","modified_gmt":"2019-05-06T14:31:22","slug":"reisetagebuch_reisealbum_gestalten","status":"publish","type":"post","link":"https:\/\/www.trend4ward.de\/trendblog\/reisetagebuch_reisealbum_gestalten\/","title":{"rendered":"Neu entdeckt: Kreatives Reisealbum &#8211; ein Ratgeberbuch"},"content":{"rendered":"<p><strong>Zeichnen, Malen, Spr\u00fchen und das mit ausgefallenen Motiven: Aus dem Christophorus Verlagshaus kommt zur diesj\u00e4hrigen Buchmesse ein neuer Kreativ-Ratgeber, der allen Bastelfreunden eine sch\u00f6ne Erinnerung an den Urlaub beschert. Das &#8222;Travel Journal&#8220;, so der Name des Buches, beinhaltet viele sch\u00f6ne Anleitungen f\u00fcr ein individuelles Reisealbum.<\/strong><!--more--><\/p>\n<p><a href=\"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/10\/Bildschirmfoto-2015-10-25-um-14.14.27.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-1667 size-medium\" src=\"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/10\/Bildschirmfoto-2015-10-25-um-14.14.27-273x300.png\" alt=\"Reisealbum\" width=\"273\" height=\"300\" srcset=\"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/10\/Bildschirmfoto-2015-10-25-um-14.14.27-273x300.png 273w, https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/10\/Bildschirmfoto-2015-10-25-um-14.14.27-55x60.png 55w, https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/10\/Bildschirmfoto-2015-10-25-um-14.14.27.png 657w\" sizes=\"auto, (max-width: 273px) 100vw, 273px\" \/><\/a>Die Autorin Daniela Schoch widmet sich exemplarisch bei den Motiven den Impressionen unterschiedlicher Ziele wie z. B.&nbsp;Tokio, Kopenhagen und Bali.&nbsp;Jedem Reiseziel &nbsp;ist eine individuell gestaltete Travel-Journal-Seite gewidmet. Dabei wird die Verwendung von verschiedenen&nbsp;Materialien mit den passenden Techniken Schritt f\u00fcr Schritt gezeigt: Collage, Gel Printing, Gestalten mit Stempeln, Schablonen, fl\u00fcssigen Farben, Stiften, Art Crayons und vielem mehr. Vorkenntnisse sind nicht notwendig und auch Einsteiger k\u00f6nnen gleich loslegen.<\/p>\n<h3 class=\"bodytext\"><strong>Travel Journal<\/strong><\/h3>\n<p class=\"bodytext\">Mein Reisealbum in Mixed Media<\/p>\n<p class=\"bodytext\">80 Seiten, \u20ac\u001f [D] 14,99, ISBN 978-3-86230-332-8<\/p>\n<p class=\"bodytext\">Mehr zum Buch und den Kreativit\u00e4tstechniken \u00e1 la &#8222;Mixed media&#8220; erfahren Sie <a href=\"http:\/\/www.christophorus-verlag.de\/de\/unsere-buecher\/malen-und-zeichnen\/mixed-media.html\" target=\"_blank\" rel=\"noopener noreferrer\">hier<\/a>.<\/p>\n<p class=\"bodytext\">&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zeichnen, Malen, Spr\u00fchen und das mit ausgefallenen Motiven: Aus dem Christophorus Verlagshaus kommt zur diesj\u00e4hrigen Buchmesse ein neuer Kreativ-Ratgeber, der allen Bastelfreunden eine sch\u00f6ne Erinnerung an den Urlaub beschert. Das &#8222;Travel Journal&#8220;, so der Name des Buches, beinhaltet viele sch\u00f6ne Anleitungen f\u00fcr ein individuelles Reisealbum.<\/p>\n","protected":false},"author":1,"featured_media":1667,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[204],"tags":[133,83,120,160,128],"class_list":["post-1665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urlaub-verreisen","tag-buchtipp","tag-diy","tag-reisefuehrer","tag-reisetrends","tag-selbermachen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neu entdeckt: Kreatives Reisealbum - ein Ratgeberbuch &#8226; trendBlog \u2013 Wohnen, Reisen, Leben und Kultur<\/title>\n<meta name=\"description\" content=\"Ein neuer Kreativ-Ratgeber, der den Urlaub versch\u00f6nert. Das &quot;Travel Journal&quot; beinhaltet viele Anleitungen f\u00fcr ein individuelles Reisealbum.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trend4ward.de\/trendblog\/reisetagebuch_reisealbum_gestalten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neu entdeckt: Kreatives Reisealbum - ein Ratgeberbuch &#8226; trendBlog \u2013 Wohnen, Reisen, Leben und Kultur\" \/>\n<meta property=\"og:description\" content=\"Ein neuer Kreativ-Ratgeber, der den Urlaub versch\u00f6nert. Das &quot;Travel Journal&quot; beinhaltet viele Anleitungen f\u00fcr ein individuelles Reisealbum.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trend4ward.de\/trendblog\/reisetagebuch_reisealbum_gestalten\/\" \/>\n<meta property=\"og:site_name\" content=\"trendBlog \u2013 Wohnen, Reisen, Leben und Kultur\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-25T13:32:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-06T14:31:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/10\/Bildschirmfoto-2015-10-25-um-14.14.27.png\" \/>\n\t<meta property=\"og:image:width\" content=\"657\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Evelyn Steinbach\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Evelyn Steinbach\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/reisetagebuch_reisealbum_gestalten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/reisetagebuch_reisealbum_gestalten\\\/\"},\"author\":{\"name\":\"Evelyn Steinbach\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/#\\\/schema\\\/person\\\/c65dd8afd2fda04893d121f31b2a8ea4\"},\"headline\":\"Neu entdeckt: Kreatives Reisealbum &#8211; ein Ratgeberbuch\",\"datePublished\":\"2015-10-25T13:32:34+00:00\",\"dateModified\":\"2019-05-06T14:31:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/reisetagebuch_reisealbum_gestalten\\\/\"},\"wordCount\":162,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/#\\\/schema\\\/person\\\/c65dd8afd2fda04893d121f31b2a8ea4\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/reisetagebuch_reisealbum_gestalten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Bildschirmfoto-2015-10-25-um-14.14.27.png\",\"keywords\":[\"Buchtipps\",\"DIY\",\"Reisef\u00fchrer\",\"Reisetrends\",\"Selbermachen\"],\"articleSection\":[\"Urlaub &amp; Verreisen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/reisetagebuch_reisealbum_gestalten\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/reisetagebuch_reisealbum_gestalten\\\/\",\"url\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/reisetagebuch_reisealbum_gestalten\\\/\",\"name\":\"Neu entdeckt: Kreatives Reisealbum - ein Ratgeberbuch &#8226; trendBlog \u2013 Wohnen, Reisen, Leben und Kultur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/reisetagebuch_reisealbum_gestalten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/reisetagebuch_reisealbum_gestalten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Bildschirmfoto-2015-10-25-um-14.14.27.png\",\"datePublished\":\"2015-10-25T13:32:34+00:00\",\"dateModified\":\"2019-05-06T14:31:22+00:00\",\"description\":\"Ein neuer Kreativ-Ratgeber, der den Urlaub versch\u00f6nert. Das \\\"Travel Journal\\\" beinhaltet viele Anleitungen f\u00fcr ein individuelles Reisealbum.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/reisetagebuch_reisealbum_gestalten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/reisetagebuch_reisealbum_gestalten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/reisetagebuch_reisealbum_gestalten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Bildschirmfoto-2015-10-25-um-14.14.27.png\",\"contentUrl\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Bildschirmfoto-2015-10-25-um-14.14.27.png\",\"width\":657,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/reisetagebuch_reisealbum_gestalten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neu entdeckt: Kreatives Reisealbum &#8211; ein Ratgeberbuch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/#website\",\"url\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/\",\"name\":\"trendBlog \u2013 Wohnen, Reisen, Leben und Kultur\",\"description\":\"Portr\u00e4ts, Reportagen, Ratgeber. Seit 2009. Von Evelyn Steinbach.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/#\\\/schema\\\/person\\\/c65dd8afd2fda04893d121f31b2a8ea4\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/#\\\/schema\\\/person\\\/c65dd8afd2fda04893d121f31b2a8ea4\",\"name\":\"Evelyn Steinbach\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/cropped-cropped-IMG_6744-e1692617617527.png\",\"url\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/cropped-cropped-IMG_6744-e1692617617527.png\",\"contentUrl\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/cropped-cropped-IMG_6744-e1692617617527.png\",\"width\":200,\"height\":183,\"caption\":\"Evelyn Steinbach\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/cropped-cropped-IMG_6744-e1692617617527.png\"},\"sameAs\":[\"http:\\\/\\\/www.trend4ward.de\"],\"url\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/author\\\/eve\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neu entdeckt: Kreatives Reisealbum - ein Ratgeberbuch &#8226; trendBlog \u2013 Wohnen, Reisen, Leben und Kultur","description":"Ein neuer Kreativ-Ratgeber, der den Urlaub versch\u00f6nert. Das \"Travel Journal\" beinhaltet viele Anleitungen f\u00fcr ein individuelles Reisealbum.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trend4ward.de\/trendblog\/reisetagebuch_reisealbum_gestalten\/","og_locale":"de_DE","og_type":"article","og_title":"Neu entdeckt: Kreatives Reisealbum - ein Ratgeberbuch &#8226; trendBlog \u2013 Wohnen, Reisen, Leben und Kultur","og_description":"Ein neuer Kreativ-Ratgeber, der den Urlaub versch\u00f6nert. Das \"Travel Journal\" beinhaltet viele Anleitungen f\u00fcr ein individuelles Reisealbum.","og_url":"https:\/\/www.trend4ward.de\/trendblog\/reisetagebuch_reisealbum_gestalten\/","og_site_name":"trendBlog \u2013 Wohnen, Reisen, Leben und Kultur","article_published_time":"2015-10-25T13:32:34+00:00","article_modified_time":"2019-05-06T14:31:22+00:00","og_image":[{"width":657,"height":721,"url":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/10\/Bildschirmfoto-2015-10-25-um-14.14.27.png","type":"image\/png"}],"author":"Evelyn Steinbach","twitter_misc":{"Verfasst von":"Evelyn Steinbach","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.trend4ward.de\/trendblog\/reisetagebuch_reisealbum_gestalten\/#article","isPartOf":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/reisetagebuch_reisealbum_gestalten\/"},"author":{"name":"Evelyn Steinbach","@id":"https:\/\/www.trend4ward.de\/trendblog\/#\/schema\/person\/c65dd8afd2fda04893d121f31b2a8ea4"},"headline":"Neu entdeckt: Kreatives Reisealbum &#8211; ein Ratgeberbuch","datePublished":"2015-10-25T13:32:34+00:00","dateModified":"2019-05-06T14:31:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/reisetagebuch_reisealbum_gestalten\/"},"wordCount":162,"commentCount":0,"publisher":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/#\/schema\/person\/c65dd8afd2fda04893d121f31b2a8ea4"},"image":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/reisetagebuch_reisealbum_gestalten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/10\/Bildschirmfoto-2015-10-25-um-14.14.27.png","keywords":["Buchtipps","DIY","Reisef\u00fchrer","Reisetrends","Selbermachen"],"articleSection":["Urlaub &amp; Verreisen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.trend4ward.de\/trendblog\/reisetagebuch_reisealbum_gestalten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.trend4ward.de\/trendblog\/reisetagebuch_reisealbum_gestalten\/","url":"https:\/\/www.trend4ward.de\/trendblog\/reisetagebuch_reisealbum_gestalten\/","name":"Neu entdeckt: Kreatives Reisealbum - ein Ratgeberbuch &#8226; trendBlog \u2013 Wohnen, Reisen, Leben und Kultur","isPartOf":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/reisetagebuch_reisealbum_gestalten\/#primaryimage"},"image":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/reisetagebuch_reisealbum_gestalten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/10\/Bildschirmfoto-2015-10-25-um-14.14.27.png","datePublished":"2015-10-25T13:32:34+00:00","dateModified":"2019-05-06T14:31:22+00:00","description":"Ein neuer Kreativ-Ratgeber, der den Urlaub versch\u00f6nert. Das \"Travel Journal\" beinhaltet viele Anleitungen f\u00fcr ein individuelles Reisealbum.","breadcrumb":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/reisetagebuch_reisealbum_gestalten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trend4ward.de\/trendblog\/reisetagebuch_reisealbum_gestalten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.trend4ward.de\/trendblog\/reisetagebuch_reisealbum_gestalten\/#primaryimage","url":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/10\/Bildschirmfoto-2015-10-25-um-14.14.27.png","contentUrl":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/10\/Bildschirmfoto-2015-10-25-um-14.14.27.png","width":657,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/www.trend4ward.de\/trendblog\/reisetagebuch_reisealbum_gestalten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.trend4ward.de\/trendblog\/"},{"@type":"ListItem","position":2,"name":"Neu entdeckt: Kreatives Reisealbum &#8211; ein Ratgeberbuch"}]},{"@type":"WebSite","@id":"https:\/\/www.trend4ward.de\/trendblog\/#website","url":"https:\/\/www.trend4ward.de\/trendblog\/","name":"trendBlog \u2013 Wohnen, Reisen, Leben und Kultur","description":"Portr\u00e4ts, Reportagen, Ratgeber. Seit 2009. Von Evelyn Steinbach.","publisher":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/#\/schema\/person\/c65dd8afd2fda04893d121f31b2a8ea4"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trend4ward.de\/trendblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.trend4ward.de\/trendblog\/#\/schema\/person\/c65dd8afd2fda04893d121f31b2a8ea4","name":"Evelyn Steinbach","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2020\/11\/cropped-cropped-IMG_6744-e1692617617527.png","url":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2020\/11\/cropped-cropped-IMG_6744-e1692617617527.png","contentUrl":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2020\/11\/cropped-cropped-IMG_6744-e1692617617527.png","width":200,"height":183,"caption":"Evelyn Steinbach"},"logo":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2020\/11\/cropped-cropped-IMG_6744-e1692617617527.png"},"sameAs":["http:\/\/www.trend4ward.de"],"url":"https:\/\/www.trend4ward.de\/trendblog\/author\/eve\/"}]}},"jetpack_featured_media_url":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2015\/10\/Bildschirmfoto-2015-10-25-um-14.14.27.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/posts\/1665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/comments?post=1665"}],"version-history":[{"count":9,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/posts\/1665\/revisions"}],"predecessor-version":[{"id":3437,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/posts\/1665\/revisions\/3437"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/media\/1667"}],"wp:attachment":[{"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/media?parent=1665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/categories?post=1665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/tags?post=1665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}