{"id":2551,"date":"2020-06-23T17:35:42","date_gmt":"2020-06-23T15:35:42","guid":{"rendered":"https:\/\/www.trend4ward.de\/trendblog\/?p=2551"},"modified":"2021-09-27T21:29:20","modified_gmt":"2021-09-27T19:29:20","slug":"tape-art-kunstwerke-mit-dem-klebeband","status":"publish","type":"post","link":"https:\/\/www.trend4ward.de\/trendblog\/tape-art-kunstwerke-mit-dem-klebeband\/","title":{"rendered":"Tape Art: Kunstwerke mit dem Klebeband"},"content":{"rendered":"<p><strong>Kleben statt Malen oder Zeichnen: Ein neuer Trend der Street Art-K\u00fcnstler h\u00e4lt nun auch in unseren vier W\u00e4nden Einzug. Denn das hierf\u00fcr verwendete Klebeband ist bunt, geruchlos und leicht angebracht. Selbst gro\u00dfe Fl\u00e4chen k\u00f6nnen damit in kurzer Zeit gestaltet werden. Und das ganz einfach mit dem Cutter. <\/strong><\/p>\n<p>Die M\u00f6glichkeiten sind hier schier unbegrenzt: von grafischen Mustern bis zu architektonischen Bildern und Gesichtsportraits &#8211; fast alles ist mit ein bisschen k\u00fcnstlerischem Geschick m\u00f6glich.\u00a0Und wem nach ein paar Monaten nach einem neuen Motiv ist, zieht das alte ganz leicht wieder von den W\u00e4nden ab &#8211; ohne R\u00fcckst\u00e4nde auf der Wand.<br \/>\n<!--more--><\/p>\n<figure id=\"attachment_2473\" aria-describedby=\"caption-attachment-2473\" style=\"width: 628px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2016\/02\/Bildschirmfoto-2016-02-24-um-15.56.39.png\" rel=\"attachment wp-att-2473\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2473 size-full\" src=\"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2016\/02\/Bildschirmfoto-2016-02-24-um-15.56.39.png\" alt=\"Tape Art\" width=\"628\" height=\"460\" srcset=\"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2016\/02\/Bildschirmfoto-2016-02-24-um-15.56.39.png 628w, https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2016\/02\/Bildschirmfoto-2016-02-24-um-15.56.39-300x220.png 300w, https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2016\/02\/Bildschirmfoto-2016-02-24-um-15.56.39-82x60.png 82w\" sizes=\"auto, (max-width: 628px) 100vw, 628px\" \/><\/a><figcaption id=\"caption-attachment-2473\" class=\"wp-caption-text\">Kindergarteneingang im Maya-Stil, Lausanne 2014<\/figcaption><\/figure>\n<p>Die Berliner Jungs alias &#8222;Klebebande&#8220; stellen in ihrem Buch &#8222;Tape Art&#8220; erstmalig die neue Kunstform vor. Sie geben einen \u00dcberblick \u00fcber die verschiedenen Klebeb\u00e4nder und erl\u00e4utern alle Techniken, die ein Tape Artist verwenden kann, um Kunstwerke zu schaffen.<\/p>\n<figure id=\"attachment_2470\" aria-describedby=\"caption-attachment-2470\" style=\"width: 260px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2016\/02\/Bildschirmfoto-2016-02-24-um-15.55.42.png\" rel=\"attachment wp-att-2470\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2470 size-medium\" src=\"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2016\/02\/Bildschirmfoto-2016-02-24-um-15.55.42-260x300.png\" alt=\"Tape Art\" width=\"260\" height=\"300\" srcset=\"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2016\/02\/Bildschirmfoto-2016-02-24-um-15.55.42-260x300.png 260w, https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2016\/02\/Bildschirmfoto-2016-02-24-um-15.55.42-52x60.png 52w, https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2016\/02\/Bildschirmfoto-2016-02-24-um-15.55.42.png 635w\" sizes=\"auto, (max-width: 260px) 100vw, 260px\" \/><\/a><figcaption id=\"caption-attachment-2470\" class=\"wp-caption-text\"><strong>Neu: TAPE ART <\/strong>Kunst mit Klebeband &#8211; Ideen und Projekte, Haupt Verlag, 168 Seiten, gebunden, durchgehend farbige Abbildungen, Preis: 39,90 \u20ac, ISBN: 978-3-258-60131-1<\/figcaption><\/figure>\n<p>Anhand von elf Projekten k\u00f6nnen Einsteiger die neue Form der Wandgestaltung kennenlernen. Foto-Anleitungen zeigen Schritt f\u00fcr Schritt, wie die Kunstwerke auf Holz, Alu-Dibond, Stoff, Stein, Asphalt oder Glas entstehen. Fortgeschrittene erhalten Anregungen f\u00fcr weitere Portraits, Landschaftsbilder und abstrakte Kunst.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Zur Entstehung des Tape Art &#8211; von den USA nach Berlin<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Tape Artisten bezeichnen ihr Schaffen als Performance-Kunst, auf deren Entstehung nicht nur der K\u00fcnstler sondern auch der Betrachter Einfluss hat. Ihre Werke dienen selten dem Selbstzweck sondern vielmehr der Interaktion und der Interpretation. 1989 nahm die junge Kunstform in Providence, Rhode Island (USA), ihren Anfang. Seit 2015 ist Berlin die unangefochtene Tape Art-Hauptstadt.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Tape Art-Kollektiv Klebebande<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Die Berliner K\u00fcnstler Nikolaj &#8222;NkoBu&#8220; Bultmann, Bruno &#8222;BeezeBoe&#8220; Kolberg und Bodo H\u00f6bing gr\u00fcndeten 2011 eine der ersten deutschen Tape Art-Vereinigungen: Die Klebebande. Thematisch besch\u00e4ftigt sich das Trio \u00fcberwiegend mit urbanen Motiven und architektonischen Strukturen &#8211; h\u00e4ufig in Gegen\u00fcberstellung zur Natur. Mehr Infos unter <a href=\"http:\/\/www.klebebande-berlin.com\" target=\"_blank\" rel=\"noopener\">www.klebebande-berlin.com<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kleben statt Malen oder Zeichnen: Ein neuer Trend der Street Art-K\u00fcnstler h\u00e4lt nun auch in unseren vier W\u00e4nden Einzug. Denn das hierf\u00fcr verwendete Klebeband ist bunt, geruchlos und leicht angebracht. Selbst gro\u00dfe Fl\u00e4chen k\u00f6nnen damit in kurzer Zeit gestaltet werden. Und das ganz einfach mit dem Cutter. Die M\u00f6glichkeiten sind hier schier unbegrenzt: von grafischen&hellip;&nbsp;<a href=\"https:\/\/www.trend4ward.de\/trendblog\/tape-art-kunstwerke-mit-dem-klebeband\/\" rel=\"bookmark\">Weiterlesen &raquo;<span class=\"screen-reader-text\">Tape Art: Kunstwerke mit dem Klebeband<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":2473,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[133,83,182,128,19],"class_list":["post-2551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wohnen","tag-buchtipp","tag-diy","tag-kunst","tag-selbermachen","tag-wand"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tape Art: Kunstwerke mit dem Klebeband &#8226; trendBlog \u2013 Wohnen, Reisen, Leben und Kultur<\/title>\n<meta name=\"description\" content=\"Kleben statt Malen oder Zeichnen: Ein neuer Trend der Street Art-K\u00fcnstler h\u00e4lt nun auch in unseren Wohnzimmern Einzug - Tape Art.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trend4ward.de\/trendblog\/tape-art-kunstwerke-mit-dem-klebeband\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tape Art: Kunstwerke mit dem Klebeband &#8226; trendBlog \u2013 Wohnen, Reisen, Leben und Kultur\" \/>\n<meta property=\"og:description\" content=\"Kleben statt Malen oder Zeichnen: Ein neuer Trend der Street Art-K\u00fcnstler h\u00e4lt nun auch in unseren Wohnzimmern Einzug - Tape Art.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trend4ward.de\/trendblog\/tape-art-kunstwerke-mit-dem-klebeband\/\" \/>\n<meta property=\"og:site_name\" content=\"trendBlog \u2013 Wohnen, Reisen, Leben und Kultur\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-23T15:35:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-27T19:29:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2016\/02\/Bildschirmfoto-2016-02-24-um-15.56.39.png\" \/>\n\t<meta property=\"og:image:width\" content=\"628\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Evelyn Steinbach\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Evelyn Steinbach\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/tape-art-kunstwerke-mit-dem-klebeband\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/tape-art-kunstwerke-mit-dem-klebeband\\\/\"},\"author\":{\"name\":\"Evelyn Steinbach\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/#\\\/schema\\\/person\\\/c65dd8afd2fda04893d121f31b2a8ea4\"},\"headline\":\"Tape Art: Kunstwerke mit dem Klebeband\",\"datePublished\":\"2020-06-23T15:35:42+00:00\",\"dateModified\":\"2021-09-27T19:29:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/tape-art-kunstwerke-mit-dem-klebeband\\\/\"},\"wordCount\":363,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/#\\\/schema\\\/person\\\/c65dd8afd2fda04893d121f31b2a8ea4\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/tape-art-kunstwerke-mit-dem-klebeband\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Bildschirmfoto-2016-02-24-um-15.56.39.png\",\"keywords\":[\"Buchtipps\",\"DIY\",\"Kunst\",\"Selbermachen\",\"Wandbel\u00e4ge\"],\"articleSection\":[\"Wohnen &amp; Einrichten\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/tape-art-kunstwerke-mit-dem-klebeband\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/tape-art-kunstwerke-mit-dem-klebeband\\\/\",\"url\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/tape-art-kunstwerke-mit-dem-klebeband\\\/\",\"name\":\"Tape Art: Kunstwerke mit dem Klebeband &#8226; trendBlog \u2013 Wohnen, Reisen, Leben und Kultur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/tape-art-kunstwerke-mit-dem-klebeband\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/tape-art-kunstwerke-mit-dem-klebeband\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Bildschirmfoto-2016-02-24-um-15.56.39.png\",\"datePublished\":\"2020-06-23T15:35:42+00:00\",\"dateModified\":\"2021-09-27T19:29:20+00:00\",\"description\":\"Kleben statt Malen oder Zeichnen: Ein neuer Trend der Street Art-K\u00fcnstler h\u00e4lt nun auch in unseren Wohnzimmern Einzug - Tape Art.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/tape-art-kunstwerke-mit-dem-klebeband\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/tape-art-kunstwerke-mit-dem-klebeband\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/tape-art-kunstwerke-mit-dem-klebeband\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Bildschirmfoto-2016-02-24-um-15.56.39.png\",\"contentUrl\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Bildschirmfoto-2016-02-24-um-15.56.39.png\",\"width\":628,\"height\":460,\"caption\":\"Kindergarteneingang im Maya-Stil, Lausanne 2014\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/tape-art-kunstwerke-mit-dem-klebeband\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tape Art: Kunstwerke mit dem Klebeband\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/#website\",\"url\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/\",\"name\":\"trendBlog \u2013 Wohnen, Reisen, Leben und Kultur\",\"description\":\"Portr\u00e4ts, Reportagen, Ratgeber. Seit 2009. Von Evelyn Steinbach.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/#\\\/schema\\\/person\\\/c65dd8afd2fda04893d121f31b2a8ea4\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/#\\\/schema\\\/person\\\/c65dd8afd2fda04893d121f31b2a8ea4\",\"name\":\"Evelyn Steinbach\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/cropped-cropped-IMG_6744-e1692617617527.png\",\"url\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/cropped-cropped-IMG_6744-e1692617617527.png\",\"contentUrl\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/cropped-cropped-IMG_6744-e1692617617527.png\",\"width\":200,\"height\":183,\"caption\":\"Evelyn Steinbach\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/cropped-cropped-IMG_6744-e1692617617527.png\"},\"sameAs\":[\"http:\\\/\\\/www.trend4ward.de\"],\"url\":\"https:\\\/\\\/www.trend4ward.de\\\/trendblog\\\/author\\\/eve\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tape Art: Kunstwerke mit dem Klebeband &#8226; trendBlog \u2013 Wohnen, Reisen, Leben und Kultur","description":"Kleben statt Malen oder Zeichnen: Ein neuer Trend der Street Art-K\u00fcnstler h\u00e4lt nun auch in unseren Wohnzimmern Einzug - Tape Art.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trend4ward.de\/trendblog\/tape-art-kunstwerke-mit-dem-klebeband\/","og_locale":"de_DE","og_type":"article","og_title":"Tape Art: Kunstwerke mit dem Klebeband &#8226; trendBlog \u2013 Wohnen, Reisen, Leben und Kultur","og_description":"Kleben statt Malen oder Zeichnen: Ein neuer Trend der Street Art-K\u00fcnstler h\u00e4lt nun auch in unseren Wohnzimmern Einzug - Tape Art.","og_url":"https:\/\/www.trend4ward.de\/trendblog\/tape-art-kunstwerke-mit-dem-klebeband\/","og_site_name":"trendBlog \u2013 Wohnen, Reisen, Leben und Kultur","article_published_time":"2020-06-23T15:35:42+00:00","article_modified_time":"2021-09-27T19:29:20+00:00","og_image":[{"width":628,"height":460,"url":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2016\/02\/Bildschirmfoto-2016-02-24-um-15.56.39.png","type":"image\/png"}],"author":"Evelyn Steinbach","twitter_misc":{"Verfasst von":"Evelyn Steinbach","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.trend4ward.de\/trendblog\/tape-art-kunstwerke-mit-dem-klebeband\/#article","isPartOf":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/tape-art-kunstwerke-mit-dem-klebeband\/"},"author":{"name":"Evelyn Steinbach","@id":"https:\/\/www.trend4ward.de\/trendblog\/#\/schema\/person\/c65dd8afd2fda04893d121f31b2a8ea4"},"headline":"Tape Art: Kunstwerke mit dem Klebeband","datePublished":"2020-06-23T15:35:42+00:00","dateModified":"2021-09-27T19:29:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/tape-art-kunstwerke-mit-dem-klebeband\/"},"wordCount":363,"commentCount":0,"publisher":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/#\/schema\/person\/c65dd8afd2fda04893d121f31b2a8ea4"},"image":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/tape-art-kunstwerke-mit-dem-klebeband\/#primaryimage"},"thumbnailUrl":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2016\/02\/Bildschirmfoto-2016-02-24-um-15.56.39.png","keywords":["Buchtipps","DIY","Kunst","Selbermachen","Wandbel\u00e4ge"],"articleSection":["Wohnen &amp; Einrichten"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.trend4ward.de\/trendblog\/tape-art-kunstwerke-mit-dem-klebeband\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.trend4ward.de\/trendblog\/tape-art-kunstwerke-mit-dem-klebeband\/","url":"https:\/\/www.trend4ward.de\/trendblog\/tape-art-kunstwerke-mit-dem-klebeband\/","name":"Tape Art: Kunstwerke mit dem Klebeband &#8226; trendBlog \u2013 Wohnen, Reisen, Leben und Kultur","isPartOf":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/tape-art-kunstwerke-mit-dem-klebeband\/#primaryimage"},"image":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/tape-art-kunstwerke-mit-dem-klebeband\/#primaryimage"},"thumbnailUrl":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2016\/02\/Bildschirmfoto-2016-02-24-um-15.56.39.png","datePublished":"2020-06-23T15:35:42+00:00","dateModified":"2021-09-27T19:29:20+00:00","description":"Kleben statt Malen oder Zeichnen: Ein neuer Trend der Street Art-K\u00fcnstler h\u00e4lt nun auch in unseren Wohnzimmern Einzug - Tape Art.","breadcrumb":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/tape-art-kunstwerke-mit-dem-klebeband\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trend4ward.de\/trendblog\/tape-art-kunstwerke-mit-dem-klebeband\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.trend4ward.de\/trendblog\/tape-art-kunstwerke-mit-dem-klebeband\/#primaryimage","url":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2016\/02\/Bildschirmfoto-2016-02-24-um-15.56.39.png","contentUrl":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2016\/02\/Bildschirmfoto-2016-02-24-um-15.56.39.png","width":628,"height":460,"caption":"Kindergarteneingang im Maya-Stil, Lausanne 2014"},{"@type":"BreadcrumbList","@id":"https:\/\/www.trend4ward.de\/trendblog\/tape-art-kunstwerke-mit-dem-klebeband\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.trend4ward.de\/trendblog\/"},{"@type":"ListItem","position":2,"name":"Tape Art: Kunstwerke mit dem Klebeband"}]},{"@type":"WebSite","@id":"https:\/\/www.trend4ward.de\/trendblog\/#website","url":"https:\/\/www.trend4ward.de\/trendblog\/","name":"trendBlog \u2013 Wohnen, Reisen, Leben und Kultur","description":"Portr\u00e4ts, Reportagen, Ratgeber. Seit 2009. Von Evelyn Steinbach.","publisher":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/#\/schema\/person\/c65dd8afd2fda04893d121f31b2a8ea4"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trend4ward.de\/trendblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.trend4ward.de\/trendblog\/#\/schema\/person\/c65dd8afd2fda04893d121f31b2a8ea4","name":"Evelyn Steinbach","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2020\/11\/cropped-cropped-IMG_6744-e1692617617527.png","url":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2020\/11\/cropped-cropped-IMG_6744-e1692617617527.png","contentUrl":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2020\/11\/cropped-cropped-IMG_6744-e1692617617527.png","width":200,"height":183,"caption":"Evelyn Steinbach"},"logo":{"@id":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2020\/11\/cropped-cropped-IMG_6744-e1692617617527.png"},"sameAs":["http:\/\/www.trend4ward.de"],"url":"https:\/\/www.trend4ward.de\/trendblog\/author\/eve\/"}]}},"jetpack_featured_media_url":"https:\/\/www.trend4ward.de\/trendblog\/wp-content\/uploads\/2016\/02\/Bildschirmfoto-2016-02-24-um-15.56.39.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/posts\/2551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/comments?post=2551"}],"version-history":[{"count":6,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/posts\/2551\/revisions"}],"predecessor-version":[{"id":5811,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/posts\/2551\/revisions\/5811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/media\/2473"}],"wp:attachment":[{"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/media?parent=2551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/categories?post=2551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trend4ward.de\/trendblog\/wp-json\/wp\/v2\/tags?post=2551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}